{"id":4082,"date":"2023-05-14T23:06:10","date_gmt":"2023-05-14T23:06:10","guid":{"rendered":"https:\/\/metrolive.tv\/ur\/?p=4082"},"modified":"2023-05-16T21:16:54","modified_gmt":"2023-05-16T21:16:54","slug":"pathaan-releases-in-bangladesh","status":"publish","type":"post","link":"https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/","title":{"rendered":"\u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u06a9\u06cc \u062a\u0627\u0631\u06cc\u062e \u0645\u06cc\u06ba \u067e\u06c1\u0644\u06cc \u0628\u0627\u0631 \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645 \u06a9\u06cc \u0646\u0645\u0627\u0626\u0634 \u06a9\u06cc \u0627\u062c\u0627\u0632\u062a"},"content":{"rendered":"\n<p class=\"has-text-align-right\">\u0641\u0644\u0645 \u0648\u0631\u0644\u0688 \u06a9\u06d2 \u0644\u06cc\u06d2 \u06cc\u06c1 \u062e\u0628\u0631 \u06a9\u0633\u06cc \u062f\u06be\u0645\u0627\u06a9\u06d2 \u0633\u06d2 \u06a9\u0645 \u0646\u06c1\u06cc\u06ba \u06c1\u06d2 \u06a9\u06c1 \u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u06a9\u06d2 \u0642\u06cc\u0627\u0645 \u06a9\u06d2 \u067e\u0686\u0627\u0633 \u0633\u0627\u0644 \u0628\u0639\u062f \u067e\u06c1\u0644\u06cc \u0645\u0631\u062a\u0628\u06c1 \u06a9\u0648\u0626\u06cc \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645 \u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u0645\u06cc\u06ba \u0631\u06cc\u0644\u06cc\u0632 \u06a9\u06cc \u06af\u0626\u06cc \u06c1\u06d2\u06d4<br>\u062f\u06cc\u06a9\u06be\u0627 \u062c\u0627\u0626\u06d2 \u062a\u0648 \u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u06a9\u0648 \u0644\u06d2 \u06a9\u0631 \u067e\u0627\u06a9\u0633\u062a\u0627\u0646 \u0627\u0648\u0631 \u0628\u06be\u0627\u0631\u062a \u0645\u06cc\u06ba \u0627\u06cc\u06a9 \u0639\u0631\u0635\u06d2 \u0633\u06d2 \u0633\u0631\u062f \u062c\u0646\u06af \u062c\u0627\u0631\u06cc \u06c1\u06d2\u06d4 \u0644\u06cc\u06a9\u0646 \u062c\u0628 \u0641\u0644\u0645\u0648\u06ba \u06a9\u06cc \u0628\u0627\u062a \u0622\u062a\u06cc \u06c1\u06d2 \u062a\u0648 \u067e\u0627\u06a9\u0633\u062a\u0627\u0646 \u0645\u06cc\u06ba \u0645\u0634\u0631\u0641 \u06a9\u06d2 \u062f\u0648\u0631 \u0645\u06cc\u06ba \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645\u0648\u06ba \u06a9\u0648 \u0646\u0645\u0627\u0626\u0634 \u06a9\u06cc \u0627\u062c\u0627\u0632\u062a \u062f\u06d2 \u062f\u06cc \u06af\u0626\u06cc \u062a\u06be\u06cc \u062c\u0628\u06a9\u06c1 \u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u062c\u0633\u06d2 \u0628\u06be\u0627\u0631\u062a \u06a9\u0627 \u06c1\u0645\u0633\u0627\u06cc\u06c1 \u06c1\u0648\u0646\u06d2 \u06a9\u06d2 \u0639\u0644\u0627\u0648\u06c1 \u0642\u0631\u06cc\u0628\u06cc \u062f\u0648\u0633\u062a \u0645\u0627\u0646\u0627 \u062c\u0627\u062a\u0627 \u06c1\u06d2\u06d4 \u0628\u0644\u06a9\u06c1 \u06cc\u06c1\u0627\u06ba \u062a\u06a9 \u06a9\u06c1\u0627 \u062c\u0627\u062a\u0627 \u06c1\u06d2 \u06a9\u06c1 \u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u06a9\u06d2 \u0633\u06cc\u0627\u0633\u06cc \u0627\u06cc\u0634\u0648\u0632 \u0633\u0645\u06cc\u062a \u06a9\u06be\u06cc\u0644\u0648\u06ba \u0627\u0648\u0631 \u062f\u06cc\u06af\u0631 \u0627\u0646\u062f\u0631\u0648\u0646\u06cc \u0645\u0639\u0627\u0645\u0644\u0627\u062a \u0645\u06cc\u06ba \u0628\u06be\u06cc \u067e\u0686\u06be\u0644\u06cc \u067e\u0627\u0646\u0686 \u062f\u06c1\u0627\u0626\u06cc\u0648\u06ba \u0645\u06cc\u06ba \u0628\u06be\u0627\u0631\u062a \u06a9\u06cc \u0645\u062f\u0627\u062e\u0644\u062a \u0631\u06c1\u06cc \u06c1\u06d2 \u0644\u06cc\u06a9\u0646 \u06cc\u06c1 \u062d\u06cc\u0631\u062a \u0627\u0646\u06af\u06cc\u0632 \u0646\u06c1\u06cc\u06ba \u06c1\u06d2 \u06a9\u06c1 \u0628\u0646\u06af\u0627\u0644\u06cc\u0648\u06ba \u0646\u06d2 \u0627\u067e\u0646\u06d2 \u0645\u0644\u06a9 \u0645\u06cc\u06ba \u0628\u0648\u0644\u06cc \u0648\u0688 \u0627\u06cc\u06a9\u0679\u0631\u0632 \u06a9\u06cc \u0632\u0628\u0631\u062f\u0633\u062a \u0641\u06cc\u0646 \u0641\u0648\u0644\u0648\u0626\u0646\u06af \u06c1\u0648\u0646\u06d2 \u06a9\u06d2 \u0628\u0627\u0648\u062c\u0648\u062f \u0627\u067e\u0646\u06d2 \u0633\u0646\u06cc\u0645\u0627\u0624\u06ba \u0645\u06cc\u06ba \u06a9\u0628\u06be\u06cc \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645 \u0644\u06af\u0646\u06d2 \u0646\u06c1\u06cc\u06ba \u062f\u06cc\u06d4 \u0644\u06cc\u06a9\u0646 \u0627\u0628 \u0644\u06af\u062a\u0627 \u06c1\u06d2 \u06a9\u06c1 \u067e\u0644\u0648\u06ba \u06a9\u06d2 \u0627\u0648\u067e\u0631 \u0633\u06d2 \u06a9\u0627\u0641\u06cc \u0633\u0627\u0631\u0627 \u067e\u0627\u0646\u06cc \u06af\u0632\u0631\u06af\u06cc\u0627 \u06c1\u06d2 \u0627\u0648\u0631 \u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634\u06cc \u062d\u06a9\u0648\u0645\u062a \u06a9\u06cc \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645\u0648\u06ba \u06a9\u06d2 \u0644\u06cc\u06d2 \u0633\u0631\u062f \u0645\u06c1\u0631\u06cc \u06a9\u06cc \u0628\u0631\u0641 \u067e\u06af\u06be\u0644\u0646\u06d2 \u0644\u06af\u06cc \u06c1\u06d2\u06d4<\/p>\n\n\n\n<script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-5684775294315332\" crossorigin=\"anonymous\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block\" data-ad-format=\"fluid\" data-ad-layout-key=\"-6t+ed+2i-1n-4w\" data-ad-client=\"ca-pub-5684775294315332\" data-ad-slot=\"8008329834\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/metrolive.tv\/ur\/wp-content\/uploads\/2023\/05\/pathaan-bangladesh-1-1024x767.jpg\" alt=\"\" class=\"wp-image-4083\"\/><\/figure>\n\n\n\n<p class=\"has-text-align-right\">\u0628\u0648\u0644\u06cc \u0648\u0688 \u06a9\u0646\u06af \u0634\u0627\u06c1 \u0631\u062e \u062e\u0627\u0646 \u06a9\u06cc \u0628\u0644\u0627\u06a9 \u0628\u0633\u0679\u0631\u0645\u0648\u0648\u06cc \u067e\u0679\u06be\u0627\u0646\u060c \u062c\u0645\u0639\u06c1 12 \u0645\u0626\u06cc \u06a9\u0648 \u0688\u06be\u0627\u06a9\u06c1 \u0645\u06cc\u06ba \u0631\u06cc\u0644\u06cc\u0632 \u06c1\u0648\u0626\u06cc \u062a\u0648\u0633\u06cc\u0646\u0645\u0627 \u06af\u06be\u0631\u0648\u06ba \u0645\u06cc\u06ba \u0644\u0648\u06af\u0648\u06ba \u06a9\u0627 \u0628\u06d2 \u067e\u0646\u0627\u06c1 \u0631\u0634 \u0646\u0638\u0631 \u0622\u06cc\u0627\u06d4 \u0646\u0635\u0641 \u0635\u062f\u06cc \u0633\u06d2 \u0632\u0627\u0626\u062f \u0639\u0631\u0635\u06d2 \u0645\u06cc\u06ba \u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u0645\u06cc\u06ba \u06a9\u0645\u0631\u0634\u0644 \u0627\u0648\u0631 \u0622\u0641\u06cc\u0634\u0644 \u0633\u0637\u062d \u067e\u0631 \u0631\u06cc\u0644\u06cc\u0632 \u06c1\u0648\u0646\u06d2 \u0648\u0627\u0644\u06cc \u06cc\u06c1 \u067e\u06c1\u0644\u06cc \u0628\u0648\u0644\u06cc \u0648\u0688 \u0641\u0644\u0645 \u06c1\u06d2\u06d4<br>\u0627\u06cc\u06a9\u0634\u0646 \u0633\u06d2 \u0628\u06be\u0631\u067e\u0648\u0631 \u0627\u0633\u067e\u0627\u0626\u06cc \u062a\u06be\u0631\u0644\u0631 \u0646\u06d2 \u062c\u0646\u0648\u0631\u06cc \u0645\u06cc\u06ba \u0631\u06cc\u0644\u06cc\u0632 \u06a9\u06d2 \u0628\u0639\u062f \u062f\u0646\u06cc\u0627 \u0628\u06be\u0631 \u0645\u06cc\u06ba \u0628\u0627\u06a9\u0633 \u0622\u0641\u0633 \u06a9\u06d2 \u0631\u06cc\u06a9\u0627\u0631\u0688 \u062a\u0648\u0691 \u0688\u0627\u0644\u06d2\u06d4<br>\u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u0646\u06d2 1971 \u0645\u06cc\u06ba \u0622\u0632\u0627\u062f\u06cc \u06a9\u06d2 \u0641\u0648\u0631\u0627\u064b \u0628\u0639\u062f \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645\u0648\u06ba \u067e\u0631 \u067e\u0627\u0628\u0646\u062f\u06cc \u0644\u06af\u0627 \u062f\u06cc \u062a\u06be\u06cc\u06d4 \u062c\u0633 \u06a9\u06d2 \u0628\u0639\u062f \u0645\u0642\u0627\u0645\u06cc \u0633\u0646\u06cc\u0645\u0627 \u0645\u0627\u0644\u06a9\u0627\u0646 \u0627\u0648\u0631 \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645 \u0645\u06cc\u06a9\u0631\u0632 \u0646\u06d2 \u06a9\u0626\u06cc \u0628\u0627\u0631 \u0627\u0633 \u062d\u0648\u0627\u0644\u06d2 \u0633\u06d2 \u0644\u0627\u0628\u0646\u06af \u06a9\u06cc \u0644\u06cc\u06a9\u0646 \u0627\u0633 \u06a9\u0627 \u0646\u062a\u06cc\u062c\u06c1 \u0628\u06d2 \u0633\u0648\u062f \u0646\u06a9\u0644\u0627\u06d4<br>\u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634\u06cc \u0633\u0646\u06cc\u0645\u0627\u0624\u06ba \u0645\u06cc\u06ba \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645\u0648\u06ba \u067e\u0631 \u067e\u0627\u0628\u0646\u062f\u06cc \u06a9\u06cc \u0627\u06cc\u06a9 \u0648\u062c\u06c1 \u062a\u0648 \u0688\u06be\u0627\u06a9\u0627 \u06a9\u06cc \u0645\u0642\u0627\u0645\u06cc \u0641\u0644\u0645\u06cc \u0635\u0646\u0639\u062a \u06a9\u0648 \u062a\u062d\u0641\u0638 \u062f\u06cc\u0646\u0627 \u062a\u06be\u0627 \u062c\u0648 \u06a9\u0633\u06cc \u0632\u0645\u0627\u0646\u06d2 \u0645\u06cc\u06ba \u0644\u0627\u06c1\u0648\u0631 \u0627\u0648\u0631 \u06a9\u0631\u0627\u0686\u06cc \u06a9\u06d2 \u06c1\u0645 \u067e\u0644\u06c1 \u0627\u0646\u0688\u0633\u0679\u0631\u06cc \u062a\u06be\u06cc \u0644\u06cc\u06a9\u0646 \u067e\u0686\u06be\u0644\u06d2 \u0686\u0646\u062f \u0633\u0627\u0644\u0648\u06ba \u0633\u06d2 \u0645\u0642\u0627\u0645\u06cc \u0641\u0644\u0645 \u0627\u0646\u0688\u0633\u0679\u0631\u06cc \u06a9\u06d2 \u0628\u062d\u0631\u0627\u0646 \u06a9\u06d2 \u0633\u0628\u0628 \u0633\u06cc\u0646\u0645\u0627 \u06af\u06be\u0631 \u0634\u062f\u06cc\u062f \u0632\u0648\u0627\u0644 \u06a9\u0627 \u0634\u06a9\u0627\u0631 \u06c1\u06cc\u06ba\u06d4 \u0645\u0633\u0644\u0633\u0644 \u063a\u06cc\u0631 \u0645\u0639\u06cc\u0627\u0631\u06cc \u0641\u0644\u0645\u0648\u06ba \u06a9\u06cc \u067e\u0631\u0648\u0688\u06a9\u0634\u0646 \u0646\u06d2 \u0644\u0648\u06af\u0648\u06ba \u06a9\u0648 \u0633\u0646\u06cc\u0645\u0627\u0624\u06ba \u0633\u06d2 \u062f\u0648\u0631 \u06a9\u0631\u062f\u06cc\u0627 \u06c1\u06d2\u06d4<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/metrolive.tv\/ur\/wp-content\/uploads\/2023\/05\/pathaan-bangladesh-1-685x1024.jpeg\" alt=\"\" class=\"wp-image-4084\"\/><\/figure>\n\n\n\n<p class=\"has-text-align-right\">\u0627\u06cc\u06a9 \u0645\u062d\u062a\u0627\u0637 \u0627\u0646\u062f\u0627\u0632\u06d2 \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u06af\u0632\u0634\u062a\u06c1 20 \u0633\u0627\u0644\u0648\u06ba \u0645\u06cc\u06ba 800 \u06a9\u06d2 \u0644\u06af \u0628\u06be\u06af \u0633\u06cc\u0646\u0645\u0627 \u06af\u06be\u0631\u0648\u06ba \u0646\u06d2 \u0627\u067e\u0646\u06d2 \u062f\u0631\u0648\u0627\u0632\u06d2 \u0628\u0646\u062f \u06a9\u0631 \u062f\u06cc\u06d2 \u06c1\u06cc\u06ba \u0627\u0648\u0631 \u0627\u0646 \u0645\u06cc\u06ba \u0633\u06d2 \u0627\u06a9\u062b\u0631 \u06a9\u0648 \u0634\u0627\u067e\u0646\u06af \u0633\u06cc\u0646\u0679\u0631\u0632 \u06cc\u0627 \u0627\u067e\u0627\u0631\u0679\u0645\u0646\u0679\u0633 \u0645\u06cc\u06ba \u062a\u0628\u062f\u06cc\u0644 \u06a9\u0631 \u062f\u06cc\u0627 \u06af\u06cc\u0627 \u06c1\u06d2\u06d4<br>\u0633\u0646 60 \u06a9\u06cc \u062f\u06c1\u0627\u0626\u06cc \u0645\u06cc\u06ba \u0633\u0646\u06cc\u0645\u0627 \u06af\u06be\u0631 \u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u06a9\u06cc \u0633\u0645\u0627\u062c\u06cc \u0632\u0646\u062f\u06af\u06cc \u06a9\u0627 \u0627\u06c1\u0645 \u0645\u0631\u06a9\u0632 \u06c1\u0648\u0627 \u06a9\u0631\u062a\u06d2 \u062a\u06be\u06d2\u06d4<\/p>\n\n\n<ul class=\"wp-block-latest-posts__list is-grid columns-3 wp-block-latest-posts\"><li><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/metrolive.tv\/ur\/2026\/05\/07\/arts-alumni-festival-2026\/\">\u062a\u06cc\u0646 \u0631\u0648\u0632\u06c1 \u2019\u2019\u0627\u0653\u0631\u0679\u0633 \u0627\u0644\u0645\u0646\u0627\u0626\u06cc \u0641\u06cc\u0633\u0679\u06cc\u0648\u0644 2026\u2018\u2018 \u06a9\u0627 \u0627\u0646\u0639\u0642\u0627\u062f \u0627\u0653\u0631\u0679\u0633 \u06a9\u0648\u0646\u0633\u0644 \u0627\u0653\u0641 \u067e\u0627\u06a9\u0633\u062a\u0627\u0646 \u06a9\u0631\u0627\u0686\u06cc \u0645\u06cc\u06ba\u00a0\u06a9\u06cc\u0627 \u062c\u0627\u0626\u06d2 \u06af\u0627<\/a><\/li>\n<li><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/metrolive.tv\/ur\/2026\/04\/27\/white-house-correspondents-dinner-incident\/\">\u0648\u0627\u0626\u0679 \u06c1\u0627\u0624\u0633 \u06a9\u0648\u0631\u06cc\u0633\u067e\u0648\u0646\u0688\u0646\u0679\u0633 \u0688\u0646\u0631 \u0648\u0627\u0642\u0639\u06c1, \u0645\u0644\u0632\u0645 \u06a9\u06cc \u0628\u06be\u0627\u0631\u062a\u06cc \u0627\u06c1\u0644\u06cc\u06c1 \u0633\u06d2 \u0645\u062a\u0639\u0644\u0642 \u0686\u0648\u0646\u06a9\u0627 \u062f\u06cc\u0646\u06d2 \u0648\u0627\u0644\u06d2 \u062f\u0639\u0648\u06d2<\/a><\/li>\n<li><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/metrolive.tv\/ur\/2026\/04\/26\/punjab-announces-modern-film-city-project-to-revive-film-industry\/\">\u067e\u0646\u062c\u0627\u0628 \u0645\u06cc\u06ba \u062c\u062f\u06cc\u062f \u0641\u0644\u0645 \u0633\u0679\u06cc \u06a9\u06d2 \u0642\u06cc\u0627\u0645 \u06a9\u0627 \u0627\u0639\u0644\u0627\u0646\u060c \u0641\u0644\u0645\u06cc \u0635\u0646\u0639\u062a \u06a9\u06cc \u0628\u062d\u0627\u0644\u06cc \u06a9\u06cc \u062c\u0627\u0646\u0628 \u0627\u06c1\u0645 \u067e\u06cc\u0634 \u0631\u0641\u062a<\/a><\/li>\n<li><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/metrolive.tv\/ur\/2026\/03\/28\/pakistan-delegation-meets-iranian-consul-general-in-karachi\/\">\u0646\u06cc\u0634\u0646\u0644 \u0645\u06cc\u0688\u06cc\u0627 \u06a9\u0644\u0628 \u06a9\u06d2 \u0648\u0641\u062f \u06a9\u06cc \u0627\u06cc\u0631\u0627\u0646\u06cc \u0642\u0648\u0646\u0635\u0644\u06cc\u0679 \u062c\u0646\u0631\u0644 \u0645\u06cc\u06ba \u0627\u06c1\u0645 \u0645\u0644\u0627\u0642\u0627\u062a<\/a><\/li>\n<li><a class=\"wp-block-latest-posts__post-title\" href=\"https:\/\/metrolive.tv\/ur\/2026\/02\/11\/national-commission-on-the-status-of-women\/\">\u0646\u062c\u06cc \u0634\u0639\u0628\u06d2 \u0645\u06cc\u06ba \u0635\u0646\u0641\u06cc \u0645\u0633\u0627\u0648\u0627\u062a \u067e\u0631 \u0635\u0648\u0628\u0627\u0626\u06cc \u0645\u0634\u0627\u0648\u0631\u062a\u06cc \u0627\u062c\u0644\u0627\u0633<\/a><\/li>\n<\/ul>\n\n\n<p class=\"has-text-align-right\">\u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634\u06cc \u062d\u06a9\u0627\u0645 \u0646\u06d2 2015 \u0645\u06cc\u06ba \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645\u0648\u06ba \u067e\u0631 \u0633\u06d2 \u067e\u0627\u0628\u0646\u062f\u06cc \u06c1\u0679\u0627\u0646\u06d2 \u06a9\u06cc \u06a9\u0648\u0634\u0634 \u06a9\u06cc \u062c\u0628 \u0628\u0648\u0644\u06cc \u0648\u0688 \u06a9\u06cc \u062f\u0648 \u06a9\u0627\u0645\u06cc\u0627\u0628 \u0641\u0644\u0645\u06cc\u06ba \u0648\u0627\u0646\u0679\u06cc\u0688\u060c \u0627\u0648\u0631\u062a\u06be\u0631\u06cc \u0627\u06cc\u0688\u06cc\u0679\u0633\u060c \u06a9\u06cc \u0646\u0645\u0627\u0626\u0634 \u06a9\u06cc \u0627\u062c\u0627\u0632\u062a \u062f\u06cc \u06af\u0626\u06cc \u0644\u06cc\u06a9\u0646 \u0645\u0642\u0627\u0645\u06cc \u0641\u0644\u0645\u06cc \u0633\u062a\u0627\u0631\u0648\u06ba \u06a9\u06d2 \u0627\u062d\u062a\u062c\u0627\u062c \u0646\u06d2 \u0633\u06cc\u0646\u0645\u0627 \u06af\u06be\u0631\u0648\u06ba \u06a9\u0648 \u0634\u0648\u0632 \u0628\u0646\u062f \u06a9\u0631\u0646\u06d2 \u067e\u0631 \u0645\u062c\u0628\u0648\u0631 \u06a9\u0631\u062f\u06cc\u0627\u06d4<br>\u062d\u06a9\u0648\u0645\u062a \u0646\u06d2 \u0628\u0627\u0644\u0627\u062e\u0631 \u06af\u0632\u0634\u062a\u06c1 \u0645\u0627\u06c1 \u0627\u06cc\u06a9 \u062d\u06a9\u0645 \u0646\u0627\u0645\u06c1 \u062c\u0627\u0631\u06cc \u06a9\u06cc\u0627 \u062c\u0633 \u0645\u06cc\u06ba \u0628\u06be\u0627\u0631\u062a \u06cc\u0627 \u062c\u0646\u0648\u0628\u06cc \u0627\u06cc\u0634\u06cc\u0627\u0626\u06cc \u0645\u0645\u0627\u0644\u06a9 \u0633\u06d2 \u0633\u0627\u0644 \u0645\u06cc\u06ba 10 \u0641\u0644\u0645\u06cc\u06ba \u062f\u0631\u0622\u0645\u062f \u06a9\u0631\u0646\u06d2 \u06a9\u06cc \u0627\u062c\u0627\u0632\u062a \u062f\u06cc \u06af\u0626\u06cc \u06c1\u06d2\u06d4<br>\u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634\u06cc \u0648\u0632\u06cc\u0631 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u062d\u0633\u0646 \u0645\u062d\u0645\u0648\u062f \u0646\u06d2 \u0627\u0633 \u062d\u0648\u0627\u0644\u06d2 \u0633\u06d2 \u0645\u06cc\u0688\u06cc\u0627 \u06a9\u0648 \u067e\u0627\u06a9\u0633\u062a\u0627\u0646 \u06a9\u06cc \u0645\u062b\u0627\u0644 \u062f\u06cc\u062a\u06d2 \u06c1\u0648\u0626\u06d2 \u06a9\u06c1\u0627 \u06a9\u06c1 \u067e\u0627\u06a9\u0633\u062a\u0627\u0646 \u0646\u06d2 \u0628\u06be\u06cc \u0627\u067e\u0646\u06cc \u0633\u0646\u06cc\u0645\u0627 \u0627\u0646\u0688\u0633\u0679\u0631\u06cc \u06a9\u0648 \u0628\u0686\u0627\u0646\u06d2 \u06a9\u06d2 \u0644\u06cc\u06d2 \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645\u06cc\u06ba \u062f\u0631\u0622\u0645\u062f \u06a9\u0631\u0646\u06d2 \u06a9\u06cc \u0627\u062c\u0627\u0632\u062a \u062f\u06cc\u06d4<br>\u067e\u0679\u06be\u0627\u0646\u060c \u06a9\u0648 \u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u06a9\u06d2 41 \u0633\u0646\u06cc\u0645\u0627 \u06af\u06be\u0631\u0648\u06ba \u0645\u06cc\u06ba \u0631\u06cc\u0644\u06cc\u0632 \u06a9\u06cc\u0627 \u06af\u06cc\u0627 \u06c1\u06d2\u06d4<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/metrolive.tv\/ur\/wp-content\/uploads\/2023\/05\/pathaan-bangladesh-2-1024x681.jpg\" alt=\"\" class=\"wp-image-4085\"\/><\/figure>\n\n\n\n<p class=\"has-text-align-right\">\u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u0645\u06cc\u06ba \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645\u0648\u06ba \u06a9\u06cc \u0646\u0645\u0627\u0626\u0634 \u06a9\u06cc \u0627\u062c\u0627\u0632\u062a \u06a9\u0648 \u06af\u06cc\u0645 \u0686\u06cc\u0646\u062c\u0631 \u0642\u0631\u0627\u0631 \u062f\u06cc\u0627 \u062c\u0627\u0631\u06c1\u0627 \u06c1\u06d2\u06d4 \u0679\u0631\u06cc\u0688 \u062c\u063a\u0627\u062f\u0631\u06cc\u0648\u06ba \u06a9\u06d2 \u0645\u0637\u0627\u0628\u0642 \u0628\u0648\u0644\u06cc \u0648\u0688 \u0627\u0648\u0631 \u0633\u0627\u0624\u062a\u06be \u0627\u0646\u0688\u06cc\u0646 \u0641\u0644\u0645\u0648\u06ba \u06a9\u06cc \u0646\u0645\u0627\u0626\u0634 \u0633\u06d2 \u0645\u0632\u06cc\u062f 200 \u0633\u06d2 300 \u0633\u0646\u06cc\u0645\u0627 \u06c1\u0627\u0644 \u06a9\u06be\u0644\u0646\u06d2 \u06a9\u06cc \u0627\u0645\u06cc\u062f \u06c1\u06d2\u06d4<br>\u062f\u0648\u0633\u0631\u06cc \u062c\u0627\u0646\u0628 \u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634\u06cc \u0641\u0644\u0645 \u0633\u0627\u0632 \u0627\u0633 \u0635\u0648\u0631\u062a \u062d\u0627\u0644 \u0633\u06d2 \u067e\u0631\u06cc\u0634\u0627\u0646 \u06c1\u06cc\u06ba\u06d4 \u06a9\u0686\u06be \u0644\u0648\u06af\u0648\u06ba \u0646\u06d2 \u0645\u0642\u0627\u0645\u06cc \u0635\u0646\u0639\u062a \u06a9\u06d2 \u062e\u0627\u062a\u0645\u06d2 \u06a9\u06cc \u0639\u0644\u0627\u0645\u062a \u06a9\u06d2 \u0644\u06cc\u06d2 \u0633\u0641\u06cc\u062f \u06a9\u0641\u0646 \u067e\u06c1\u0646 \u06a9\u0631 \u0627\u062d\u062a\u062c\u0627\u062c \u06a9\u0631\u0646\u06d2 \u06a9\u06cc \u062f\u06be\u0645\u06a9\u06cc \u0628\u06be\u06cc \u062f\u06cc \u06c1\u06d2\u06d4<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"\ud835\udc0f\ud835\udc1a\ud835\udc2d\ud835\udc21\ud835\udc1a\ud835\udc1a\ud835\udc27 \ud835\udc22\ud835\udc27 \ud835\udc01\ud835\udc1a\ud835\udc27\ud835\udc20\ud835\udc25\ud835\udc1a\ud835\udc1d\ud835\udc1e\ud835\udc2c\ud835\udc21 | \ud835\udc05\ud835\udc22\ud835\udc2b\ud835\udc2c\ud835\udc2d \ud835\udc08\ud835\udc27\ud835\udc1d\ud835\udc22\ud835\udc1a\ud835\udc27 \ud835\udc1f\ud835\udc22\ud835\udc25\ud835\udc26 \ud835\udc2d\ud835\udc28 \ud835\udc1b\ud835\udc1e \ud835\udc2b\ud835\udc1e\ud835\udc25\ud835\udc1e\ud835\udc1a\ud835\udc2c\ud835\udc1e\ud835\udc1d \ud835\udc22\ud835\udc27 \ud835\udc01\ud835\udc1a\ud835\udc27\ud835\udc20\ud835\udc25\ud835\udc1a\ud835\udc1d\ud835\udc1e\ud835\udc2c\ud835\udc21 \ud835\udc22\ud835\udc27 \ud835\udfd3\ud835\udfce \ud835\udc32\ud835\udc1e\ud835\udc1a\ud835\udc2b\ud835\udc2c | \ud835\udc12\ud835\udc21\ud835\udc1a\ud835\udc21\ud835\udc2b\ud835\udc2e\ud835\udc24\ud835\udc21 \ud835\udc0a\ud835\udc21\ud835\udc1a\ud835\udc27\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/C4JOgIwqy58?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-5684775294315332\" crossorigin=\"anonymous\"><\/script>\n<ins class=\"adsbygoogle\" style=\"display:block\" data-ad-format=\"fluid\" data-ad-layout-key=\"-6t+ed+2i-1n-4w\" data-ad-client=\"ca-pub-5684775294315332\" data-ad-slot=\"8008329834\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0641\u0644\u0645 \u0648\u0631\u0644\u0688 \u06a9\u06d2 \u0644\u06cc\u06d2 \u06cc\u06c1 \u062e\u0628\u0631 \u06a9\u0633\u06cc \u062f\u06be\u0645\u0627\u06a9\u06d2 \u0633\u06d2 \u06a9\u0645 \u0646\u06c1\u06cc\u06ba \u06c1\u06d2 \u06a9\u06c1 \u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u06a9\u06d2 \u0642\u06cc\u0627\u0645 \u06a9\u06d2 \u067e\u0686\u0627\u0633 \u0633\u0627\u0644 \u0628\u0639\u062f \u067e\u06c1\u0644\u06cc \u0645\u0631\u062a\u0628\u06c1 \u06a9\u0648\u0626\u06cc \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645 \u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u0645\u06cc\u06ba \u0631\u06cc\u0644\u06cc\u0632 \u06a9\u06cc \u06af\u0626\u06cc \u06c1\u06d2\u06d4\u062f\u06cc\u06a9\u06be\u0627 \u062c\u0627\u0626\u06d2 \u062a\u0648 \u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u06a9\u0648 \u0644\u06d2 \u06a9\u0631 \u067e\u0627\u06a9\u0633\u062a\u0627\u0646 \u0627\u0648\u0631 \u0628\u06be\u0627\u0631\u062a \u0645\u06cc\u06ba \u0627\u06cc\u06a9 \u0639\u0631\u0635\u06d2 \u0633\u06d2 \u0633\u0631\u062f \u062c\u0646\u06af \u062c\u0627\u0631\u06cc \u06c1\u06d2\u06d4 \u0644\u06cc\u06a9\u0646 \u062c\u0628 \u0641\u0644\u0645\u0648\u06ba \u06a9\u06cc [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[3],"tags":[546,396],"class_list":{"0":"post-4082","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-news","7":"tag-546","8":"tag-396"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u06a9\u06cc \u062a\u0627\u0631\u06cc\u062e \u0645\u06cc\u06ba \u067e\u06c1\u0644\u06cc \u0628\u0627\u0631 \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645 \u06a9\u06cc \u0646\u0645\u0627\u0626\u0634 \u06a9\u06cc \u0627\u062c\u0627\u0632\u062a - Metro Live<\/title>\n<meta name=\"description\" content=\"\u0628\u0648\u0644\u06cc \u0648\u0688 \u06a9\u0646\u06af \u0634\u0627\u06c1 \u0631\u062e \u062e\u0627\u0646 \u06a9\u06cc \u0628\u0644\u0627\u06a9 \u0628\u0633\u0679\u0631\u0645\u0648\u0648\u06cc \u067e\u0679\u06be\u0627\u0646\u060c \u062c\u0645\u0639\u06c1 12 \u0645\u0626\u06cc \u06a9\u0648 \u0688\u06be\u0627\u06a9\u06c1 \u0645\u06cc\u06ba \u0631\u06cc\u0644\u06cc\u0632 \u06c1\u0648\u0626\u06cc \u062a\u0648\u0633\u06cc\u0646\u0645\u0627 \u06af\u06be\u0631\u0648\u06ba \u0645\u06cc\u06ba \u0644\u0648\u06af\u0648\u06ba \u06a9\u0627 \u0628\u06d2 \u067e\u0646\u0627\u06c1 \u0631\u0634 \u0646\u0638\u0631 \u0622\u06cc\u0627\u06d4 \u0646\u0635\u0641 \u0635\u062f\u06cc \u0633\u06d2 \u0632\u0627\u0626\u062f \u0639\u0631\u0635\u06d2 \u0645\u06cc\u06ba \u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u0645\u06cc\u06ba \u06a9\u0645\u0631\u0634\u0644 \u0627\u0648\u0631 \u0622\u0641\u06cc\u0634\u0644 \u0633\u0637\u062d \u067e\u0631 \u0631\u06cc\u0644\u06cc\u0632 \u06c1\u0648\u0646\u06d2 \u0648\u0627\u0644\u06cc \u06cc\u06c1 \u067e\u06c1\u0644\u06cc \u0628\u0648\u0644\u06cc \u0648\u0688 \u0641\u0644\u0645 \u06c1\u06d2\u06d4\u0627\u06cc\u06a9\u0634\u0646 \u0633\u06d2 \u0628\u06be\u0631\u067e\u0648\u0631 \u0627\u0633\u067e\u0627\u0626\u06cc \u062a\u06be\u0631\u0644\u0631 \u0646\u06d2 \u062c\u0646\u0648\u0631\u06cc \u0645\u06cc\u06ba \u0631\u06cc\u0644\u06cc\u0632 \u06a9\u06d2 \u0628\u0639\u062f \u062f\u0646\u06cc\u0627 \u0628\u06be\u0631 \u0645\u06cc\u06ba \u0628\u0627\u06a9\u0633 \u0622\u0641\u0633 \u06a9\u06d2 \u0631\u06cc\u06a9\u0627\u0631\u0688 \u062a\u0648\u0691 \u0688\u0627\u0644\u06d2\u06d4\u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u0646\u06d2 1971 \u0645\u06cc\u06ba \u0622\u0632\u0627\u062f\u06cc \u06a9\u06d2 \u0641\u0648\u0631\u0627\u064b \u0628\u0639\u062f \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645\u0648\u06ba \u067e\u0631 \u067e\u0627\u0628\u0646\u062f\u06cc \u0644\u06af\u0627 \u062f\u06cc \u062a\u06be\u06cc\u06d4 \u062c\u0633 \u06a9\u06d2 \u0628\u0639\u062f \u0645\u0642\u0627\u0645\u06cc \u0633\u0646\u06cc\u0645\u0627 \u0645\u0627\u0644\u06a9\u0627\u0646 \u0627\u0648\u0631 \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645 \u0645\u06cc\u06a9\u0631\u0632 \u0646\u06d2 \u06a9\u0626\u06cc \u0628\u0627\u0631 \u0627\u0633 \u062d\u0648\u0627\u0644\u06d2 \u0633\u06d2 \u0644\u0627\u0628\u0646\u06af \u06a9\u06cc \u0644\u06cc\u06a9\u0646 \u0627\u0633 \u06a9\u0627 \u0646\u062a\u06cc\u062c\u06c1 \u0628\u06d2 \u0633\u0648\u062f \u0646\u06a9\u0644\u0627\u06d4\u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634\u06cc \u0633\u0646\u06cc\u0645\u0627\u0624\u06ba \u0645\u06cc\u06ba \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645\u0648\u06ba \u067e\u0631 \u067e\u0627\u0628\u0646\u062f\u06cc \u06a9\u06cc \u0627\u06cc\u06a9 \u0648\u062c\u06c1 \u062a\u0648 \u0688\u06be\u0627\u06a9\u0627 \u06a9\u06cc \u0645\u0642\u0627\u0645\u06cc \u0641\u0644\u0645\u06cc \u0635\u0646\u0639\u062a \u06a9\u0648 \u062a\u062d\u0641\u0638 \u062f\u06cc\u0646\u0627 \u062a\u06be\u0627 \u062c\u0648 \u06a9\u0633\u06cc \u0632\u0645\u0627\u0646\u06d2 \u0645\u06cc\u06ba \u0644\u0627\u06c1\u0648\u0631 \u0627\u0648\u0631 \u06a9\u0631\u0627\u0686\u06cc \u06a9\u06d2 \u06c1\u0645 \u067e\u0644\u06c1 \u0627\u0646\u0688\u0633\u0679\u0631\u06cc \u062a\u06be\u06cc \u0644\u06cc\u06a9\u0646 \u067e\u0686\u06be\u0644\u06d2 \u0686\u0646\u062f \u0633\u0627\u0644\u0648\u06ba \u0633\u06d2 \u0645\u0642\u0627\u0645\u06cc \u0641\u0644\u0645 \u0627\u0646\u0688\u0633\u0679\u0631\u06cc \u06a9\u06d2 \u0628\u062d\u0631\u0627\u0646 \u06a9\u06d2 \u0633\u0628\u0628 \u0633\u06cc\u0646\u0645\u0627 \u06af\u06be\u0631 \u0634\u062f\u06cc\u062f \u0632\u0648\u0627\u0644 \u06a9\u0627 \u0634\u06a9\u0627\u0631 \u06c1\u06cc\u06ba\u06d4 \u0645\u0633\u0644\u0633\u0644 \u063a\u06cc\u0631 \u0645\u0639\u06cc\u0627\u0631\u06cc \u0641\u0644\u0645\u0648\u06ba \u06a9\u06cc \u067e\u0631\u0648\u0688\u06a9\u0634\u0646 \u0646\u06d2 \u0644\u0648\u06af\u0648\u06ba \u06a9\u0648 \u0633\u0646\u06cc\u0645\u0627\u0624\u06ba \u0633\u06d2 \u062f\u0648\u0631 \u06a9\u0631\u062f\u06cc\u0627 \u06c1\u06d2\u06d4\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u06a9\u06cc \u062a\u0627\u0631\u06cc\u062e \u0645\u06cc\u06ba \u067e\u06c1\u0644\u06cc \u0628\u0627\u0631 \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645 \u06a9\u06cc \u0646\u0645\u0627\u0626\u0634 \u06a9\u06cc \u0627\u062c\u0627\u0632\u062a - Metro Live\" \/>\n<meta property=\"og:description\" content=\"\u0628\u0648\u0644\u06cc \u0648\u0688 \u06a9\u0646\u06af \u0634\u0627\u06c1 \u0631\u062e \u062e\u0627\u0646 \u06a9\u06cc \u0628\u0644\u0627\u06a9 \u0628\u0633\u0679\u0631\u0645\u0648\u0648\u06cc \u067e\u0679\u06be\u0627\u0646\u060c \u062c\u0645\u0639\u06c1 12 \u0645\u0626\u06cc \u06a9\u0648 \u0688\u06be\u0627\u06a9\u06c1 \u0645\u06cc\u06ba \u0631\u06cc\u0644\u06cc\u0632 \u06c1\u0648\u0626\u06cc \u062a\u0648\u0633\u06cc\u0646\u0645\u0627 \u06af\u06be\u0631\u0648\u06ba \u0645\u06cc\u06ba \u0644\u0648\u06af\u0648\u06ba \u06a9\u0627 \u0628\u06d2 \u067e\u0646\u0627\u06c1 \u0631\u0634 \u0646\u0638\u0631 \u0622\u06cc\u0627\u06d4 \u0646\u0635\u0641 \u0635\u062f\u06cc \u0633\u06d2 \u0632\u0627\u0626\u062f \u0639\u0631\u0635\u06d2 \u0645\u06cc\u06ba \u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u0645\u06cc\u06ba \u06a9\u0645\u0631\u0634\u0644 \u0627\u0648\u0631 \u0622\u0641\u06cc\u0634\u0644 \u0633\u0637\u062d \u067e\u0631 \u0631\u06cc\u0644\u06cc\u0632 \u06c1\u0648\u0646\u06d2 \u0648\u0627\u0644\u06cc \u06cc\u06c1 \u067e\u06c1\u0644\u06cc \u0628\u0648\u0644\u06cc \u0648\u0688 \u0641\u0644\u0645 \u06c1\u06d2\u06d4\u0627\u06cc\u06a9\u0634\u0646 \u0633\u06d2 \u0628\u06be\u0631\u067e\u0648\u0631 \u0627\u0633\u067e\u0627\u0626\u06cc \u062a\u06be\u0631\u0644\u0631 \u0646\u06d2 \u062c\u0646\u0648\u0631\u06cc \u0645\u06cc\u06ba \u0631\u06cc\u0644\u06cc\u0632 \u06a9\u06d2 \u0628\u0639\u062f \u062f\u0646\u06cc\u0627 \u0628\u06be\u0631 \u0645\u06cc\u06ba \u0628\u0627\u06a9\u0633 \u0622\u0641\u0633 \u06a9\u06d2 \u0631\u06cc\u06a9\u0627\u0631\u0688 \u062a\u0648\u0691 \u0688\u0627\u0644\u06d2\u06d4\u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u0646\u06d2 1971 \u0645\u06cc\u06ba \u0622\u0632\u0627\u062f\u06cc \u06a9\u06d2 \u0641\u0648\u0631\u0627\u064b \u0628\u0639\u062f \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645\u0648\u06ba \u067e\u0631 \u067e\u0627\u0628\u0646\u062f\u06cc \u0644\u06af\u0627 \u062f\u06cc \u062a\u06be\u06cc\u06d4 \u062c\u0633 \u06a9\u06d2 \u0628\u0639\u062f \u0645\u0642\u0627\u0645\u06cc \u0633\u0646\u06cc\u0645\u0627 \u0645\u0627\u0644\u06a9\u0627\u0646 \u0627\u0648\u0631 \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645 \u0645\u06cc\u06a9\u0631\u0632 \u0646\u06d2 \u06a9\u0626\u06cc \u0628\u0627\u0631 \u0627\u0633 \u062d\u0648\u0627\u0644\u06d2 \u0633\u06d2 \u0644\u0627\u0628\u0646\u06af \u06a9\u06cc \u0644\u06cc\u06a9\u0646 \u0627\u0633 \u06a9\u0627 \u0646\u062a\u06cc\u062c\u06c1 \u0628\u06d2 \u0633\u0648\u062f \u0646\u06a9\u0644\u0627\u06d4\u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634\u06cc \u0633\u0646\u06cc\u0645\u0627\u0624\u06ba \u0645\u06cc\u06ba \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645\u0648\u06ba \u067e\u0631 \u067e\u0627\u0628\u0646\u062f\u06cc \u06a9\u06cc \u0627\u06cc\u06a9 \u0648\u062c\u06c1 \u062a\u0648 \u0688\u06be\u0627\u06a9\u0627 \u06a9\u06cc \u0645\u0642\u0627\u0645\u06cc \u0641\u0644\u0645\u06cc \u0635\u0646\u0639\u062a \u06a9\u0648 \u062a\u062d\u0641\u0638 \u062f\u06cc\u0646\u0627 \u062a\u06be\u0627 \u062c\u0648 \u06a9\u0633\u06cc \u0632\u0645\u0627\u0646\u06d2 \u0645\u06cc\u06ba \u0644\u0627\u06c1\u0648\u0631 \u0627\u0648\u0631 \u06a9\u0631\u0627\u0686\u06cc \u06a9\u06d2 \u06c1\u0645 \u067e\u0644\u06c1 \u0627\u0646\u0688\u0633\u0679\u0631\u06cc \u062a\u06be\u06cc \u0644\u06cc\u06a9\u0646 \u067e\u0686\u06be\u0644\u06d2 \u0686\u0646\u062f \u0633\u0627\u0644\u0648\u06ba \u0633\u06d2 \u0645\u0642\u0627\u0645\u06cc \u0641\u0644\u0645 \u0627\u0646\u0688\u0633\u0679\u0631\u06cc \u06a9\u06d2 \u0628\u062d\u0631\u0627\u0646 \u06a9\u06d2 \u0633\u0628\u0628 \u0633\u06cc\u0646\u0645\u0627 \u06af\u06be\u0631 \u0634\u062f\u06cc\u062f \u0632\u0648\u0627\u0644 \u06a9\u0627 \u0634\u06a9\u0627\u0631 \u06c1\u06cc\u06ba\u06d4 \u0645\u0633\u0644\u0633\u0644 \u063a\u06cc\u0631 \u0645\u0639\u06cc\u0627\u0631\u06cc \u0641\u0644\u0645\u0648\u06ba \u06a9\u06cc \u067e\u0631\u0648\u0688\u06a9\u0634\u0646 \u0646\u06d2 \u0644\u0648\u06af\u0648\u06ba \u06a9\u0648 \u0633\u0646\u06cc\u0645\u0627\u0624\u06ba \u0633\u06d2 \u062f\u0648\u0631 \u06a9\u0631\u062f\u06cc\u0627 \u06c1\u06d2\u06d4\" \/>\n<meta property=\"og:url\" content=\"https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/\" \/>\n<meta property=\"og:site_name\" content=\"Metro Live\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-14T23:06:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-16T21:16:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/metrolive.tv\/ur\/wp-content\/uploads\/2023\/05\/pathaan-bangladesh-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u0646\u06cc\u0648\u0632 \u0688\u06cc\u0633\u06a9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0646\u06cc\u0648\u0632 \u0688\u06cc\u0633\u06a9\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/\"},\"author\":{\"name\":\"\u0646\u06cc\u0648\u0632 \u0688\u06cc\u0633\u06a9\",\"@id\":\"https:\/\/metrolive.tv\/ur\/#\/schema\/person\/9110fb5bec97948d7cae2fe31892bae2\"},\"headline\":\"\u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u06a9\u06cc \u062a\u0627\u0631\u06cc\u062e \u0645\u06cc\u06ba \u067e\u06c1\u0644\u06cc \u0628\u0627\u0631 \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645 \u06a9\u06cc \u0646\u0645\u0627\u0626\u0634 \u06a9\u06cc \u0627\u062c\u0627\u0632\u062a\",\"datePublished\":\"2023-05-14T23:06:10+00:00\",\"dateModified\":\"2023-05-16T21:16:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/\"},\"wordCount\":5,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/metrolive.tv\/ur\/#\/schema\/person\/9110fb5bec97948d7cae2fe31892bae2\"},\"image\":{\"@id\":\"https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/metrolive.tv\/ur\/wp-content\/uploads\/2023\/05\/pathaan-bangladesh-1-1024x767.jpg\",\"keywords\":[\"\u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u067e\u0679\u06be\u0627\u0646\",\"\u067e\u0679\u06be\u0627\u0646\"],\"articleSection\":[\"\u062e\u0628\u0631\u06cc\u06ba\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/\",\"url\":\"https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/\",\"name\":\"\u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u06a9\u06cc \u062a\u0627\u0631\u06cc\u062e \u0645\u06cc\u06ba \u067e\u06c1\u0644\u06cc \u0628\u0627\u0631 \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645 \u06a9\u06cc \u0646\u0645\u0627\u0626\u0634 \u06a9\u06cc \u0627\u062c\u0627\u0632\u062a - Metro Live\",\"isPartOf\":{\"@id\":\"https:\/\/metrolive.tv\/ur\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/metrolive.tv\/ur\/wp-content\/uploads\/2023\/05\/pathaan-bangladesh-1-1024x767.jpg\",\"datePublished\":\"2023-05-14T23:06:10+00:00\",\"dateModified\":\"2023-05-16T21:16:54+00:00\",\"description\":\"\u0628\u0648\u0644\u06cc \u0648\u0688 \u06a9\u0646\u06af \u0634\u0627\u06c1 \u0631\u062e \u062e\u0627\u0646 \u06a9\u06cc \u0628\u0644\u0627\u06a9 \u0628\u0633\u0679\u0631\u0645\u0648\u0648\u06cc \u067e\u0679\u06be\u0627\u0646\u060c \u062c\u0645\u0639\u06c1 12 \u0645\u0626\u06cc \u06a9\u0648 \u0688\u06be\u0627\u06a9\u06c1 \u0645\u06cc\u06ba \u0631\u06cc\u0644\u06cc\u0632 \u06c1\u0648\u0626\u06cc \u062a\u0648\u0633\u06cc\u0646\u0645\u0627 \u06af\u06be\u0631\u0648\u06ba \u0645\u06cc\u06ba \u0644\u0648\u06af\u0648\u06ba \u06a9\u0627 \u0628\u06d2 \u067e\u0646\u0627\u06c1 \u0631\u0634 \u0646\u0638\u0631 \u0622\u06cc\u0627\u06d4 \u0646\u0635\u0641 \u0635\u062f\u06cc \u0633\u06d2 \u0632\u0627\u0626\u062f \u0639\u0631\u0635\u06d2 \u0645\u06cc\u06ba \u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u0645\u06cc\u06ba \u06a9\u0645\u0631\u0634\u0644 \u0627\u0648\u0631 \u0622\u0641\u06cc\u0634\u0644 \u0633\u0637\u062d \u067e\u0631 \u0631\u06cc\u0644\u06cc\u0632 \u06c1\u0648\u0646\u06d2 \u0648\u0627\u0644\u06cc \u06cc\u06c1 \u067e\u06c1\u0644\u06cc \u0628\u0648\u0644\u06cc \u0648\u0688 \u0641\u0644\u0645 \u06c1\u06d2\u06d4\u0627\u06cc\u06a9\u0634\u0646 \u0633\u06d2 \u0628\u06be\u0631\u067e\u0648\u0631 \u0627\u0633\u067e\u0627\u0626\u06cc \u062a\u06be\u0631\u0644\u0631 \u0646\u06d2 \u062c\u0646\u0648\u0631\u06cc \u0645\u06cc\u06ba \u0631\u06cc\u0644\u06cc\u0632 \u06a9\u06d2 \u0628\u0639\u062f \u062f\u0646\u06cc\u0627 \u0628\u06be\u0631 \u0645\u06cc\u06ba \u0628\u0627\u06a9\u0633 \u0622\u0641\u0633 \u06a9\u06d2 \u0631\u06cc\u06a9\u0627\u0631\u0688 \u062a\u0648\u0691 \u0688\u0627\u0644\u06d2\u06d4\u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u0646\u06d2 1971 \u0645\u06cc\u06ba \u0622\u0632\u0627\u062f\u06cc \u06a9\u06d2 \u0641\u0648\u0631\u0627\u064b \u0628\u0639\u062f \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645\u0648\u06ba \u067e\u0631 \u067e\u0627\u0628\u0646\u062f\u06cc \u0644\u06af\u0627 \u062f\u06cc \u062a\u06be\u06cc\u06d4 \u062c\u0633 \u06a9\u06d2 \u0628\u0639\u062f \u0645\u0642\u0627\u0645\u06cc \u0633\u0646\u06cc\u0645\u0627 \u0645\u0627\u0644\u06a9\u0627\u0646 \u0627\u0648\u0631 \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645 \u0645\u06cc\u06a9\u0631\u0632 \u0646\u06d2 \u06a9\u0626\u06cc \u0628\u0627\u0631 \u0627\u0633 \u062d\u0648\u0627\u0644\u06d2 \u0633\u06d2 \u0644\u0627\u0628\u0646\u06af \u06a9\u06cc \u0644\u06cc\u06a9\u0646 \u0627\u0633 \u06a9\u0627 \u0646\u062a\u06cc\u062c\u06c1 \u0628\u06d2 \u0633\u0648\u062f \u0646\u06a9\u0644\u0627\u06d4\u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634\u06cc \u0633\u0646\u06cc\u0645\u0627\u0624\u06ba \u0645\u06cc\u06ba \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645\u0648\u06ba \u067e\u0631 \u067e\u0627\u0628\u0646\u062f\u06cc \u06a9\u06cc \u0627\u06cc\u06a9 \u0648\u062c\u06c1 \u062a\u0648 \u0688\u06be\u0627\u06a9\u0627 \u06a9\u06cc \u0645\u0642\u0627\u0645\u06cc \u0641\u0644\u0645\u06cc \u0635\u0646\u0639\u062a \u06a9\u0648 \u062a\u062d\u0641\u0638 \u062f\u06cc\u0646\u0627 \u062a\u06be\u0627 \u062c\u0648 \u06a9\u0633\u06cc \u0632\u0645\u0627\u0646\u06d2 \u0645\u06cc\u06ba \u0644\u0627\u06c1\u0648\u0631 \u0627\u0648\u0631 \u06a9\u0631\u0627\u0686\u06cc \u06a9\u06d2 \u06c1\u0645 \u067e\u0644\u06c1 \u0627\u0646\u0688\u0633\u0679\u0631\u06cc \u062a\u06be\u06cc \u0644\u06cc\u06a9\u0646 \u067e\u0686\u06be\u0644\u06d2 \u0686\u0646\u062f \u0633\u0627\u0644\u0648\u06ba \u0633\u06d2 \u0645\u0642\u0627\u0645\u06cc \u0641\u0644\u0645 \u0627\u0646\u0688\u0633\u0679\u0631\u06cc \u06a9\u06d2 \u0628\u062d\u0631\u0627\u0646 \u06a9\u06d2 \u0633\u0628\u0628 \u0633\u06cc\u0646\u0645\u0627 \u06af\u06be\u0631 \u0634\u062f\u06cc\u062f \u0632\u0648\u0627\u0644 \u06a9\u0627 \u0634\u06a9\u0627\u0631 \u06c1\u06cc\u06ba\u06d4 \u0645\u0633\u0644\u0633\u0644 \u063a\u06cc\u0631 \u0645\u0639\u06cc\u0627\u0631\u06cc \u0641\u0644\u0645\u0648\u06ba \u06a9\u06cc \u067e\u0631\u0648\u0688\u06a9\u0634\u0646 \u0646\u06d2 \u0644\u0648\u06af\u0648\u06ba \u06a9\u0648 \u0633\u0646\u06cc\u0645\u0627\u0624\u06ba \u0633\u06d2 \u062f\u0648\u0631 \u06a9\u0631\u062f\u06cc\u0627 \u06c1\u06d2\u06d4\",\"breadcrumb\":{\"@id\":\"https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/#primaryimage\",\"url\":\"https:\/\/metrolive.tv\/ur\/wp-content\/uploads\/2023\/05\/pathaan-bangladesh-1-1024x767.jpg\",\"contentUrl\":\"https:\/\/metrolive.tv\/ur\/wp-content\/uploads\/2023\/05\/pathaan-bangladesh-1-1024x767.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/metrolive.tv\/ur\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u06a9\u06cc \u062a\u0627\u0631\u06cc\u062e \u0645\u06cc\u06ba \u067e\u06c1\u0644\u06cc \u0628\u0627\u0631 \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645 \u06a9\u06cc \u0646\u0645\u0627\u0626\u0634 \u06a9\u06cc \u0627\u062c\u0627\u0632\u062a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/metrolive.tv\/ur\/#website\",\"url\":\"https:\/\/metrolive.tv\/ur\/\",\"name\":\"Metro Live\",\"description\":\"Pakistan&#039;s Leading Entertainment Magazine, Video &amp; News Portal\",\"publisher\":{\"@id\":\"https:\/\/metrolive.tv\/ur\/#\/schema\/person\/9110fb5bec97948d7cae2fe31892bae2\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/metrolive.tv\/ur\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/metrolive.tv\/ur\/#\/schema\/person\/9110fb5bec97948d7cae2fe31892bae2\",\"name\":\"\u0646\u06cc\u0648\u0632 \u0688\u06cc\u0633\u06a9\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/metrolive.tv\/ur\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/metrolive.tv\/ur\/wp-content\/uploads\/2022\/05\/Metro-live-3D-Logo-white-copy-scaled.jpg\",\"contentUrl\":\"https:\/\/metrolive.tv\/ur\/wp-content\/uploads\/2022\/05\/Metro-live-3D-Logo-white-copy-scaled.jpg\",\"width\":2449,\"height\":2560,\"caption\":\"\u0646\u06cc\u0648\u0632 \u0688\u06cc\u0633\u06a9\"},\"logo\":{\"@id\":\"https:\/\/metrolive.tv\/ur\/#\/schema\/person\/image\/\"},\"sameAs\":[\"https:\/\/metrolive.tv\/ur\"],\"url\":\"https:\/\/metrolive.tv\/ur\/author\/metroliveurdu\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u06a9\u06cc \u062a\u0627\u0631\u06cc\u062e \u0645\u06cc\u06ba \u067e\u06c1\u0644\u06cc \u0628\u0627\u0631 \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645 \u06a9\u06cc \u0646\u0645\u0627\u0626\u0634 \u06a9\u06cc \u0627\u062c\u0627\u0632\u062a - Metro Live","description":"\u0628\u0648\u0644\u06cc \u0648\u0688 \u06a9\u0646\u06af \u0634\u0627\u06c1 \u0631\u062e \u062e\u0627\u0646 \u06a9\u06cc \u0628\u0644\u0627\u06a9 \u0628\u0633\u0679\u0631\u0645\u0648\u0648\u06cc \u067e\u0679\u06be\u0627\u0646\u060c \u062c\u0645\u0639\u06c1 12 \u0645\u0626\u06cc \u06a9\u0648 \u0688\u06be\u0627\u06a9\u06c1 \u0645\u06cc\u06ba \u0631\u06cc\u0644\u06cc\u0632 \u06c1\u0648\u0626\u06cc \u062a\u0648\u0633\u06cc\u0646\u0645\u0627 \u06af\u06be\u0631\u0648\u06ba \u0645\u06cc\u06ba \u0644\u0648\u06af\u0648\u06ba \u06a9\u0627 \u0628\u06d2 \u067e\u0646\u0627\u06c1 \u0631\u0634 \u0646\u0638\u0631 \u0622\u06cc\u0627\u06d4 \u0646\u0635\u0641 \u0635\u062f\u06cc \u0633\u06d2 \u0632\u0627\u0626\u062f \u0639\u0631\u0635\u06d2 \u0645\u06cc\u06ba \u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u0645\u06cc\u06ba \u06a9\u0645\u0631\u0634\u0644 \u0627\u0648\u0631 \u0622\u0641\u06cc\u0634\u0644 \u0633\u0637\u062d \u067e\u0631 \u0631\u06cc\u0644\u06cc\u0632 \u06c1\u0648\u0646\u06d2 \u0648\u0627\u0644\u06cc \u06cc\u06c1 \u067e\u06c1\u0644\u06cc \u0628\u0648\u0644\u06cc \u0648\u0688 \u0641\u0644\u0645 \u06c1\u06d2\u06d4\u0627\u06cc\u06a9\u0634\u0646 \u0633\u06d2 \u0628\u06be\u0631\u067e\u0648\u0631 \u0627\u0633\u067e\u0627\u0626\u06cc \u062a\u06be\u0631\u0644\u0631 \u0646\u06d2 \u062c\u0646\u0648\u0631\u06cc \u0645\u06cc\u06ba \u0631\u06cc\u0644\u06cc\u0632 \u06a9\u06d2 \u0628\u0639\u062f \u062f\u0646\u06cc\u0627 \u0628\u06be\u0631 \u0645\u06cc\u06ba \u0628\u0627\u06a9\u0633 \u0622\u0641\u0633 \u06a9\u06d2 \u0631\u06cc\u06a9\u0627\u0631\u0688 \u062a\u0648\u0691 \u0688\u0627\u0644\u06d2\u06d4\u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u0646\u06d2 1971 \u0645\u06cc\u06ba \u0622\u0632\u0627\u062f\u06cc \u06a9\u06d2 \u0641\u0648\u0631\u0627\u064b \u0628\u0639\u062f \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645\u0648\u06ba \u067e\u0631 \u067e\u0627\u0628\u0646\u062f\u06cc \u0644\u06af\u0627 \u062f\u06cc \u062a\u06be\u06cc\u06d4 \u062c\u0633 \u06a9\u06d2 \u0628\u0639\u062f \u0645\u0642\u0627\u0645\u06cc \u0633\u0646\u06cc\u0645\u0627 \u0645\u0627\u0644\u06a9\u0627\u0646 \u0627\u0648\u0631 \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645 \u0645\u06cc\u06a9\u0631\u0632 \u0646\u06d2 \u06a9\u0626\u06cc \u0628\u0627\u0631 \u0627\u0633 \u062d\u0648\u0627\u0644\u06d2 \u0633\u06d2 \u0644\u0627\u0628\u0646\u06af \u06a9\u06cc \u0644\u06cc\u06a9\u0646 \u0627\u0633 \u06a9\u0627 \u0646\u062a\u06cc\u062c\u06c1 \u0628\u06d2 \u0633\u0648\u062f \u0646\u06a9\u0644\u0627\u06d4\u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634\u06cc \u0633\u0646\u06cc\u0645\u0627\u0624\u06ba \u0645\u06cc\u06ba \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645\u0648\u06ba \u067e\u0631 \u067e\u0627\u0628\u0646\u062f\u06cc \u06a9\u06cc \u0627\u06cc\u06a9 \u0648\u062c\u06c1 \u062a\u0648 \u0688\u06be\u0627\u06a9\u0627 \u06a9\u06cc \u0645\u0642\u0627\u0645\u06cc \u0641\u0644\u0645\u06cc \u0635\u0646\u0639\u062a \u06a9\u0648 \u062a\u062d\u0641\u0638 \u062f\u06cc\u0646\u0627 \u062a\u06be\u0627 \u062c\u0648 \u06a9\u0633\u06cc \u0632\u0645\u0627\u0646\u06d2 \u0645\u06cc\u06ba \u0644\u0627\u06c1\u0648\u0631 \u0627\u0648\u0631 \u06a9\u0631\u0627\u0686\u06cc \u06a9\u06d2 \u06c1\u0645 \u067e\u0644\u06c1 \u0627\u0646\u0688\u0633\u0679\u0631\u06cc \u062a\u06be\u06cc \u0644\u06cc\u06a9\u0646 \u067e\u0686\u06be\u0644\u06d2 \u0686\u0646\u062f \u0633\u0627\u0644\u0648\u06ba \u0633\u06d2 \u0645\u0642\u0627\u0645\u06cc \u0641\u0644\u0645 \u0627\u0646\u0688\u0633\u0679\u0631\u06cc \u06a9\u06d2 \u0628\u062d\u0631\u0627\u0646 \u06a9\u06d2 \u0633\u0628\u0628 \u0633\u06cc\u0646\u0645\u0627 \u06af\u06be\u0631 \u0634\u062f\u06cc\u062f \u0632\u0648\u0627\u0644 \u06a9\u0627 \u0634\u06a9\u0627\u0631 \u06c1\u06cc\u06ba\u06d4 \u0645\u0633\u0644\u0633\u0644 \u063a\u06cc\u0631 \u0645\u0639\u06cc\u0627\u0631\u06cc \u0641\u0644\u0645\u0648\u06ba \u06a9\u06cc \u067e\u0631\u0648\u0688\u06a9\u0634\u0646 \u0646\u06d2 \u0644\u0648\u06af\u0648\u06ba \u06a9\u0648 \u0633\u0646\u06cc\u0645\u0627\u0624\u06ba \u0633\u06d2 \u062f\u0648\u0631 \u06a9\u0631\u062f\u06cc\u0627 \u06c1\u06d2\u06d4","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/","og_locale":"en_US","og_type":"article","og_title":"\u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u06a9\u06cc \u062a\u0627\u0631\u06cc\u062e \u0645\u06cc\u06ba \u067e\u06c1\u0644\u06cc \u0628\u0627\u0631 \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645 \u06a9\u06cc \u0646\u0645\u0627\u0626\u0634 \u06a9\u06cc \u0627\u062c\u0627\u0632\u062a - Metro Live","og_description":"\u0628\u0648\u0644\u06cc \u0648\u0688 \u06a9\u0646\u06af \u0634\u0627\u06c1 \u0631\u062e \u062e\u0627\u0646 \u06a9\u06cc \u0628\u0644\u0627\u06a9 \u0628\u0633\u0679\u0631\u0645\u0648\u0648\u06cc \u067e\u0679\u06be\u0627\u0646\u060c \u062c\u0645\u0639\u06c1 12 \u0645\u0626\u06cc \u06a9\u0648 \u0688\u06be\u0627\u06a9\u06c1 \u0645\u06cc\u06ba \u0631\u06cc\u0644\u06cc\u0632 \u06c1\u0648\u0626\u06cc \u062a\u0648\u0633\u06cc\u0646\u0645\u0627 \u06af\u06be\u0631\u0648\u06ba \u0645\u06cc\u06ba \u0644\u0648\u06af\u0648\u06ba \u06a9\u0627 \u0628\u06d2 \u067e\u0646\u0627\u06c1 \u0631\u0634 \u0646\u0638\u0631 \u0622\u06cc\u0627\u06d4 \u0646\u0635\u0641 \u0635\u062f\u06cc \u0633\u06d2 \u0632\u0627\u0626\u062f \u0639\u0631\u0635\u06d2 \u0645\u06cc\u06ba \u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u0645\u06cc\u06ba \u06a9\u0645\u0631\u0634\u0644 \u0627\u0648\u0631 \u0622\u0641\u06cc\u0634\u0644 \u0633\u0637\u062d \u067e\u0631 \u0631\u06cc\u0644\u06cc\u0632 \u06c1\u0648\u0646\u06d2 \u0648\u0627\u0644\u06cc \u06cc\u06c1 \u067e\u06c1\u0644\u06cc \u0628\u0648\u0644\u06cc \u0648\u0688 \u0641\u0644\u0645 \u06c1\u06d2\u06d4\u0627\u06cc\u06a9\u0634\u0646 \u0633\u06d2 \u0628\u06be\u0631\u067e\u0648\u0631 \u0627\u0633\u067e\u0627\u0626\u06cc \u062a\u06be\u0631\u0644\u0631 \u0646\u06d2 \u062c\u0646\u0648\u0631\u06cc \u0645\u06cc\u06ba \u0631\u06cc\u0644\u06cc\u0632 \u06a9\u06d2 \u0628\u0639\u062f \u062f\u0646\u06cc\u0627 \u0628\u06be\u0631 \u0645\u06cc\u06ba \u0628\u0627\u06a9\u0633 \u0622\u0641\u0633 \u06a9\u06d2 \u0631\u06cc\u06a9\u0627\u0631\u0688 \u062a\u0648\u0691 \u0688\u0627\u0644\u06d2\u06d4\u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u0646\u06d2 1971 \u0645\u06cc\u06ba \u0622\u0632\u0627\u062f\u06cc \u06a9\u06d2 \u0641\u0648\u0631\u0627\u064b \u0628\u0639\u062f \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645\u0648\u06ba \u067e\u0631 \u067e\u0627\u0628\u0646\u062f\u06cc \u0644\u06af\u0627 \u062f\u06cc \u062a\u06be\u06cc\u06d4 \u062c\u0633 \u06a9\u06d2 \u0628\u0639\u062f \u0645\u0642\u0627\u0645\u06cc \u0633\u0646\u06cc\u0645\u0627 \u0645\u0627\u0644\u06a9\u0627\u0646 \u0627\u0648\u0631 \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645 \u0645\u06cc\u06a9\u0631\u0632 \u0646\u06d2 \u06a9\u0626\u06cc \u0628\u0627\u0631 \u0627\u0633 \u062d\u0648\u0627\u0644\u06d2 \u0633\u06d2 \u0644\u0627\u0628\u0646\u06af \u06a9\u06cc \u0644\u06cc\u06a9\u0646 \u0627\u0633 \u06a9\u0627 \u0646\u062a\u06cc\u062c\u06c1 \u0628\u06d2 \u0633\u0648\u062f \u0646\u06a9\u0644\u0627\u06d4\u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634\u06cc \u0633\u0646\u06cc\u0645\u0627\u0624\u06ba \u0645\u06cc\u06ba \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645\u0648\u06ba \u067e\u0631 \u067e\u0627\u0628\u0646\u062f\u06cc \u06a9\u06cc \u0627\u06cc\u06a9 \u0648\u062c\u06c1 \u062a\u0648 \u0688\u06be\u0627\u06a9\u0627 \u06a9\u06cc \u0645\u0642\u0627\u0645\u06cc \u0641\u0644\u0645\u06cc \u0635\u0646\u0639\u062a \u06a9\u0648 \u062a\u062d\u0641\u0638 \u062f\u06cc\u0646\u0627 \u062a\u06be\u0627 \u062c\u0648 \u06a9\u0633\u06cc \u0632\u0645\u0627\u0646\u06d2 \u0645\u06cc\u06ba \u0644\u0627\u06c1\u0648\u0631 \u0627\u0648\u0631 \u06a9\u0631\u0627\u0686\u06cc \u06a9\u06d2 \u06c1\u0645 \u067e\u0644\u06c1 \u0627\u0646\u0688\u0633\u0679\u0631\u06cc \u062a\u06be\u06cc \u0644\u06cc\u06a9\u0646 \u067e\u0686\u06be\u0644\u06d2 \u0686\u0646\u062f \u0633\u0627\u0644\u0648\u06ba \u0633\u06d2 \u0645\u0642\u0627\u0645\u06cc \u0641\u0644\u0645 \u0627\u0646\u0688\u0633\u0679\u0631\u06cc \u06a9\u06d2 \u0628\u062d\u0631\u0627\u0646 \u06a9\u06d2 \u0633\u0628\u0628 \u0633\u06cc\u0646\u0645\u0627 \u06af\u06be\u0631 \u0634\u062f\u06cc\u062f \u0632\u0648\u0627\u0644 \u06a9\u0627 \u0634\u06a9\u0627\u0631 \u06c1\u06cc\u06ba\u06d4 \u0645\u0633\u0644\u0633\u0644 \u063a\u06cc\u0631 \u0645\u0639\u06cc\u0627\u0631\u06cc \u0641\u0644\u0645\u0648\u06ba \u06a9\u06cc \u067e\u0631\u0648\u0688\u06a9\u0634\u0646 \u0646\u06d2 \u0644\u0648\u06af\u0648\u06ba \u06a9\u0648 \u0633\u0646\u06cc\u0645\u0627\u0624\u06ba \u0633\u06d2 \u062f\u0648\u0631 \u06a9\u0631\u062f\u06cc\u0627 \u06c1\u06d2\u06d4","og_url":"https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/","og_site_name":"Metro Live","article_published_time":"2023-05-14T23:06:10+00:00","article_modified_time":"2023-05-16T21:16:54+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/metrolive.tv\/ur\/wp-content\/uploads\/2023\/05\/pathaan-bangladesh-3.jpg","type":"image\/jpeg"}],"author":"\u0646\u06cc\u0648\u0632 \u0688\u06cc\u0633\u06a9","twitter_card":"summary_large_image","twitter_misc":{"Written by":"\u0646\u06cc\u0648\u0632 \u0688\u06cc\u0633\u06a9","Est. reading time":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/#article","isPartOf":{"@id":"https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/"},"author":{"name":"\u0646\u06cc\u0648\u0632 \u0688\u06cc\u0633\u06a9","@id":"https:\/\/metrolive.tv\/ur\/#\/schema\/person\/9110fb5bec97948d7cae2fe31892bae2"},"headline":"\u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u06a9\u06cc \u062a\u0627\u0631\u06cc\u062e \u0645\u06cc\u06ba \u067e\u06c1\u0644\u06cc \u0628\u0627\u0631 \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645 \u06a9\u06cc \u0646\u0645\u0627\u0626\u0634 \u06a9\u06cc \u0627\u062c\u0627\u0632\u062a","datePublished":"2023-05-14T23:06:10+00:00","dateModified":"2023-05-16T21:16:54+00:00","mainEntityOfPage":{"@id":"https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/"},"wordCount":5,"commentCount":0,"publisher":{"@id":"https:\/\/metrolive.tv\/ur\/#\/schema\/person\/9110fb5bec97948d7cae2fe31892bae2"},"image":{"@id":"https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/#primaryimage"},"thumbnailUrl":"https:\/\/metrolive.tv\/ur\/wp-content\/uploads\/2023\/05\/pathaan-bangladesh-1-1024x767.jpg","keywords":["\u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u067e\u0679\u06be\u0627\u0646","\u067e\u0679\u06be\u0627\u0646"],"articleSection":["\u062e\u0628\u0631\u06cc\u06ba"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/","url":"https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/","name":"\u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u06a9\u06cc \u062a\u0627\u0631\u06cc\u062e \u0645\u06cc\u06ba \u067e\u06c1\u0644\u06cc \u0628\u0627\u0631 \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645 \u06a9\u06cc \u0646\u0645\u0627\u0626\u0634 \u06a9\u06cc \u0627\u062c\u0627\u0632\u062a - Metro Live","isPartOf":{"@id":"https:\/\/metrolive.tv\/ur\/#website"},"primaryImageOfPage":{"@id":"https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/#primaryimage"},"image":{"@id":"https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/#primaryimage"},"thumbnailUrl":"https:\/\/metrolive.tv\/ur\/wp-content\/uploads\/2023\/05\/pathaan-bangladesh-1-1024x767.jpg","datePublished":"2023-05-14T23:06:10+00:00","dateModified":"2023-05-16T21:16:54+00:00","description":"\u0628\u0648\u0644\u06cc \u0648\u0688 \u06a9\u0646\u06af \u0634\u0627\u06c1 \u0631\u062e \u062e\u0627\u0646 \u06a9\u06cc \u0628\u0644\u0627\u06a9 \u0628\u0633\u0679\u0631\u0645\u0648\u0648\u06cc \u067e\u0679\u06be\u0627\u0646\u060c \u062c\u0645\u0639\u06c1 12 \u0645\u0626\u06cc \u06a9\u0648 \u0688\u06be\u0627\u06a9\u06c1 \u0645\u06cc\u06ba \u0631\u06cc\u0644\u06cc\u0632 \u06c1\u0648\u0626\u06cc \u062a\u0648\u0633\u06cc\u0646\u0645\u0627 \u06af\u06be\u0631\u0648\u06ba \u0645\u06cc\u06ba \u0644\u0648\u06af\u0648\u06ba \u06a9\u0627 \u0628\u06d2 \u067e\u0646\u0627\u06c1 \u0631\u0634 \u0646\u0638\u0631 \u0622\u06cc\u0627\u06d4 \u0646\u0635\u0641 \u0635\u062f\u06cc \u0633\u06d2 \u0632\u0627\u0626\u062f \u0639\u0631\u0635\u06d2 \u0645\u06cc\u06ba \u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u0645\u06cc\u06ba \u06a9\u0645\u0631\u0634\u0644 \u0627\u0648\u0631 \u0622\u0641\u06cc\u0634\u0644 \u0633\u0637\u062d \u067e\u0631 \u0631\u06cc\u0644\u06cc\u0632 \u06c1\u0648\u0646\u06d2 \u0648\u0627\u0644\u06cc \u06cc\u06c1 \u067e\u06c1\u0644\u06cc \u0628\u0648\u0644\u06cc \u0648\u0688 \u0641\u0644\u0645 \u06c1\u06d2\u06d4\u0627\u06cc\u06a9\u0634\u0646 \u0633\u06d2 \u0628\u06be\u0631\u067e\u0648\u0631 \u0627\u0633\u067e\u0627\u0626\u06cc \u062a\u06be\u0631\u0644\u0631 \u0646\u06d2 \u062c\u0646\u0648\u0631\u06cc \u0645\u06cc\u06ba \u0631\u06cc\u0644\u06cc\u0632 \u06a9\u06d2 \u0628\u0639\u062f \u062f\u0646\u06cc\u0627 \u0628\u06be\u0631 \u0645\u06cc\u06ba \u0628\u0627\u06a9\u0633 \u0622\u0641\u0633 \u06a9\u06d2 \u0631\u06cc\u06a9\u0627\u0631\u0688 \u062a\u0648\u0691 \u0688\u0627\u0644\u06d2\u06d4\u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u0646\u06d2 1971 \u0645\u06cc\u06ba \u0622\u0632\u0627\u062f\u06cc \u06a9\u06d2 \u0641\u0648\u0631\u0627\u064b \u0628\u0639\u062f \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645\u0648\u06ba \u067e\u0631 \u067e\u0627\u0628\u0646\u062f\u06cc \u0644\u06af\u0627 \u062f\u06cc \u062a\u06be\u06cc\u06d4 \u062c\u0633 \u06a9\u06d2 \u0628\u0639\u062f \u0645\u0642\u0627\u0645\u06cc \u0633\u0646\u06cc\u0645\u0627 \u0645\u0627\u0644\u06a9\u0627\u0646 \u0627\u0648\u0631 \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645 \u0645\u06cc\u06a9\u0631\u0632 \u0646\u06d2 \u06a9\u0626\u06cc \u0628\u0627\u0631 \u0627\u0633 \u062d\u0648\u0627\u0644\u06d2 \u0633\u06d2 \u0644\u0627\u0628\u0646\u06af \u06a9\u06cc \u0644\u06cc\u06a9\u0646 \u0627\u0633 \u06a9\u0627 \u0646\u062a\u06cc\u062c\u06c1 \u0628\u06d2 \u0633\u0648\u062f \u0646\u06a9\u0644\u0627\u06d4\u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634\u06cc \u0633\u0646\u06cc\u0645\u0627\u0624\u06ba \u0645\u06cc\u06ba \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645\u0648\u06ba \u067e\u0631 \u067e\u0627\u0628\u0646\u062f\u06cc \u06a9\u06cc \u0627\u06cc\u06a9 \u0648\u062c\u06c1 \u062a\u0648 \u0688\u06be\u0627\u06a9\u0627 \u06a9\u06cc \u0645\u0642\u0627\u0645\u06cc \u0641\u0644\u0645\u06cc \u0635\u0646\u0639\u062a \u06a9\u0648 \u062a\u062d\u0641\u0638 \u062f\u06cc\u0646\u0627 \u062a\u06be\u0627 \u062c\u0648 \u06a9\u0633\u06cc \u0632\u0645\u0627\u0646\u06d2 \u0645\u06cc\u06ba \u0644\u0627\u06c1\u0648\u0631 \u0627\u0648\u0631 \u06a9\u0631\u0627\u0686\u06cc \u06a9\u06d2 \u06c1\u0645 \u067e\u0644\u06c1 \u0627\u0646\u0688\u0633\u0679\u0631\u06cc \u062a\u06be\u06cc \u0644\u06cc\u06a9\u0646 \u067e\u0686\u06be\u0644\u06d2 \u0686\u0646\u062f \u0633\u0627\u0644\u0648\u06ba \u0633\u06d2 \u0645\u0642\u0627\u0645\u06cc \u0641\u0644\u0645 \u0627\u0646\u0688\u0633\u0679\u0631\u06cc \u06a9\u06d2 \u0628\u062d\u0631\u0627\u0646 \u06a9\u06d2 \u0633\u0628\u0628 \u0633\u06cc\u0646\u0645\u0627 \u06af\u06be\u0631 \u0634\u062f\u06cc\u062f \u0632\u0648\u0627\u0644 \u06a9\u0627 \u0634\u06a9\u0627\u0631 \u06c1\u06cc\u06ba\u06d4 \u0645\u0633\u0644\u0633\u0644 \u063a\u06cc\u0631 \u0645\u0639\u06cc\u0627\u0631\u06cc \u0641\u0644\u0645\u0648\u06ba \u06a9\u06cc \u067e\u0631\u0648\u0688\u06a9\u0634\u0646 \u0646\u06d2 \u0644\u0648\u06af\u0648\u06ba \u06a9\u0648 \u0633\u0646\u06cc\u0645\u0627\u0624\u06ba \u0633\u06d2 \u062f\u0648\u0631 \u06a9\u0631\u062f\u06cc\u0627 \u06c1\u06d2\u06d4","breadcrumb":{"@id":"https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/#primaryimage","url":"https:\/\/metrolive.tv\/ur\/wp-content\/uploads\/2023\/05\/pathaan-bangladesh-1-1024x767.jpg","contentUrl":"https:\/\/metrolive.tv\/ur\/wp-content\/uploads\/2023\/05\/pathaan-bangladesh-1-1024x767.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/metrolive.tv\/ur\/2023\/05\/14\/pathaan-releases-in-bangladesh\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/metrolive.tv\/ur\/"},{"@type":"ListItem","position":2,"name":"\u0628\u0646\u06af\u0644\u06c1 \u062f\u06cc\u0634 \u06a9\u06cc \u062a\u0627\u0631\u06cc\u062e \u0645\u06cc\u06ba \u067e\u06c1\u0644\u06cc \u0628\u0627\u0631 \u0628\u06be\u0627\u0631\u062a\u06cc \u0641\u0644\u0645 \u06a9\u06cc \u0646\u0645\u0627\u0626\u0634 \u06a9\u06cc \u0627\u062c\u0627\u0632\u062a"}]},{"@type":"WebSite","@id":"https:\/\/metrolive.tv\/ur\/#website","url":"https:\/\/metrolive.tv\/ur\/","name":"Metro Live","description":"Pakistan&#039;s Leading Entertainment Magazine, Video &amp; News Portal","publisher":{"@id":"https:\/\/metrolive.tv\/ur\/#\/schema\/person\/9110fb5bec97948d7cae2fe31892bae2"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/metrolive.tv\/ur\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/metrolive.tv\/ur\/#\/schema\/person\/9110fb5bec97948d7cae2fe31892bae2","name":"\u0646\u06cc\u0648\u0632 \u0688\u06cc\u0633\u06a9","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/metrolive.tv\/ur\/#\/schema\/person\/image\/","url":"https:\/\/metrolive.tv\/ur\/wp-content\/uploads\/2022\/05\/Metro-live-3D-Logo-white-copy-scaled.jpg","contentUrl":"https:\/\/metrolive.tv\/ur\/wp-content\/uploads\/2022\/05\/Metro-live-3D-Logo-white-copy-scaled.jpg","width":2449,"height":2560,"caption":"\u0646\u06cc\u0648\u0632 \u0688\u06cc\u0633\u06a9"},"logo":{"@id":"https:\/\/metrolive.tv\/ur\/#\/schema\/person\/image\/"},"sameAs":["https:\/\/metrolive.tv\/ur"],"url":"https:\/\/metrolive.tv\/ur\/author\/metroliveurdu\/"}]}},"_links":{"self":[{"href":"https:\/\/metrolive.tv\/ur\/wp-json\/wp\/v2\/posts\/4082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/metrolive.tv\/ur\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/metrolive.tv\/ur\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/metrolive.tv\/ur\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/metrolive.tv\/ur\/wp-json\/wp\/v2\/comments?post=4082"}],"version-history":[{"count":0,"href":"https:\/\/metrolive.tv\/ur\/wp-json\/wp\/v2\/posts\/4082\/revisions"}],"wp:attachment":[{"href":"https:\/\/metrolive.tv\/ur\/wp-json\/wp\/v2\/media?parent=4082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/metrolive.tv\/ur\/wp-json\/wp\/v2\/categories?post=4082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/metrolive.tv\/ur\/wp-json\/wp\/v2\/tags?post=4082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}